{"id":2,"date":"2019-09-12T09:58:14","date_gmt":"2019-09-12T07:58:14","guid":{"rendered":"https:\/\/flow-zeichenwettbewerb.de\/?page_id=2"},"modified":"2026-06-17T20:03:14","modified_gmt":"2026-06-17T18:03:14","slug":"beispiel-seite","status":"publish","type":"page","link":"https:\/\/flow-zeichenwettbewerb.de\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-122379-bg row-container boomapps_vcrow\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"video-container\">\n<iframe\n  width=\"560\"\n  height=\"315\"\n  src=\"https:\/\/www.youtube.com\/embed\/InaRzVcxEMw\"\n  title=\"YouTube video player\"\n  frameborder=\"0\"\n  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\"\n  allowfullscreen>\n<\/iframe>\n\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"empty-space empty-single\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"uncode-single-media  text-center animate_when_almost_visible top-t-bottom\"><div class=\"single-wrapper\" style=\"max-width: 40%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-2844\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/08\/FLOW_Logo_DE_WHITE_4C.png\" width=\"354\" height=\"232\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/08\/FLOW_Logo_DE_WHITE_4C.png 354w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/08\/FLOW_Logo_DE_WHITE_4C-300x197.png 300w\" sizes=\"(max-width: 354px) 100vw, 354px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-double\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-120807-bg row-container boomapps_vcrow\" id=\"row-unique-1\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-double\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_row style-color-355101-bg row-internal row-container boomapps_vcrow\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-4 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-4009\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei.png\" width=\"807\" height=\"1144\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei.png 807w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei-212x300.png 212w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei-722x1024.png 722w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei-768x1089.png 768w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei-8x12.png 8w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/2505-Yalcinkaya-Bilge-Asli-16-Jahre-Tuerkei-350x496.png 350w\" sizes=\"(max-width: 807px) 100vw, 807px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-4 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-4021\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-scaled.jpg\" width=\"1810\" height=\"2560\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-scaled.jpg 1810w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-212x300.jpg 212w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-724x1024.jpg 724w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-768x1086.jpg 768w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-1086x1536.jpg 1086w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-1448x2048.jpg 1448w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-8x12.jpg 8w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-350x495.jpg 350w\" sizes=\"(max-width: 1810px) 100vw, 1810px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_child col-lg-4 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-3964\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min.png\" width=\"794\" height=\"1126\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min.png 794w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min-212x300.png 212w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min-722x1024.png 722w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min-768x1089.png 768w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min-8x12.png 8w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/341-Julia-Wichary-10-Jahre-Deutschland-min-350x496.png 350w\" sizes=\"(max-width: 794px) 100vw, 794px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-triple\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-355101-bg limit-width boxed-row row-container boomapps_vcrow\" id=\"row-unique-2\"><div class=\"row row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-triple\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><h1 class=\"h1\" ><span>Ausstellungen 2026<\/span><\/h1><\/div><div class=\"clear\"><\/div><\/div>\n\t<div class=\"wpb_raw_code wpb_raw_html \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"ausstellung-wrapper\">\n\n    <div class=\"viewport\">\n        <div class=\"track\" id=\"track\"><\/div>\n    <\/div>\n\n<\/div>\n\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", function () {\n\n    const ausstellungen = [\n        { name: \"Bunt ist meine Welt\u2026oder doch nicht immer?\", datum: \"ab 21. Januar 2026\", ort: \"Kundencenter der Wohnbauten GmbH Schwedt\/Oder\" },\n        { name: \"Retrospektive 58. Internationaler Zeichenwettbewerb \/ Sonderwettbewerb Baumalleen\", datum: \"16. M\u00e4rz bis 16. Mai 2026\", ort: \"Musik- und Kunstschule J. A. P. Schulz Schwedt\/Oder\" },\n        { name: \"59. Jahresausstellung FLOW\", datum: \"25. August bis 07. September 2026\", ort: \"Uckerm\u00e4rkische B\u00fchnen Schwedt\" }\n    ];\n\n    const track = document.getElementById(\"track\");\n\n    const slides = [...ausstellungen, ...ausstellungen];\n\n    slides.forEach(a => {\n        const el = document.createElement(\"div\");\n        el.className = \"slide\";\n        el.innerHTML = `\n            <h3>${a.name}<\/h3>\n        `;\n        track.appendChild(el);\n    });\n\n    let position = 0;\n    let speed = 0.2;\n    let paused = false;\n\n    function animate() {\n        if (!paused) {\n            position -= speed;\n            if (Math.abs(position) >= track.scrollWidth \/ 2) {\n                position = 0;\n            }\n            track.style.transform = `translateX(${position}px)`;\n        }\n        requestAnimationFrame(animate);\n    }\n\n    animate();\n\n    const wrapper = document.querySelector(\".ausstellung-wrapper\");\n    wrapper.addEventListener(\"mouseenter\", () => paused = true);\n    wrapper.addEventListener(\"mouseleave\", () => paused = false);\n\n    const zielURL = \"https:\/\/flow-zeichenwettbewerb.de\/ausstellungen\/\";\n    wrapper.addEventListener(\"click\", () => {\n        window.location.href = zielURL;\n    });\n\n});\n<\/script>\n\n\n<style>\n.ausstellung-wrapper {\n    position: relative;\n    overflow: hidden;\n    width: 50vw;\n    cursor: pointer; \/* \ud83d\udc48 Hand-Cursor *\/\n}\n\n\/* Optional: dezenter Hover-Effekt *\/\n.ausstellung-wrapper:hover {\n    opacity: 0.9;\n}\n\n.slide {\n    min-width: 360px;\n    padding: 20px;\n    box-sizing: border-box;\n}\n\n.viewport {\n    overflow: hidden;\n}\n\n.track {\n    display: flex;\n    gap: 40px;\n    padding: 20px;\n    will-change: transform;\n}\n\n<\/style>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"empty-space empty-quad\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-2\" data-row=\"script-row-unique-2\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-2\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-vyce-bg row-container boomapps_vcrow\" id=\"row-unique-3\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row shift_y_neg_triple row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-4 boomapps_vccolumn col-sm-25 single-internal-gutter\"><div class=\"uncol style-light shift_x_neg_half\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1663172816170 boomapps_vccolumn border-color-120807-color single-block-padding style-color-120807-bg has-bg\" style=\"padding-top: 20px ;padding-right: 20px ;padding-bottom: 20px ;padding-left: 20px ;\" ><div class=\"uncont\" style=\" max-width:60%;\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><a class=\"single-media-link\" href=\"https:\/\/www.youtube.com\/channel\/UC0HlUju9YgviF_bbHIimj2Q\" target=\"_blank\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-2908\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Youtube-Icon.png\" width=\"500\" height=\"500\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Youtube-Icon.png 500w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Youtube-Icon-300x300.png 300w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Youtube-Icon-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div><\/div><a class=\"col-link custom-link\" href=\"https:\/\/www.youtube.com\/channel\/UC0HlUju9YgviF_bbHIimj2Q\" target=\"_blank\" title=\"\"><\/a><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-4 boomapps_vccolumn col-sm-25 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1663172875799 boomapps_vccolumn single-block-padding style-color-152864-bg has-bg\" style=\"padding-top: 20px ;padding-right: 20px ;padding-bottom: 20px ;padding-left: 20px ;\" ><div class=\"uncont\" style=\" max-width:60%;\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-2909\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Insta-Icon-1.png\" width=\"500\" height=\"500\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Insta-Icon-1.png 500w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Insta-Icon-1-300x300.png 300w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Insta-Icon-1-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><a class=\"col-link custom-link\" href=\"https:\/\/www.instagram.com\/flowcompetition\/\" target=\"_blank\" title=\"\"><\/a><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-4 boomapps_vccolumn col-sm-25 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1663172842969 boomapps_vccolumn single-block-padding style-color-370045-bg has-bg\" style=\"padding-top: 20px ;padding-right: 20px ;padding-bottom: 20px ;padding-left: 20px ;\" ><div class=\"uncont\" style=\" max-width:60%;\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-2905\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Facebook-Icons.png\" width=\"500\" height=\"500\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Facebook-Icons.png 500w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Facebook-Icons-300x300.png 300w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2022\/09\/Facebook-Icons-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><a class=\"col-link custom-link\" href=\"https:\/\/www.facebook.com\/flowcompetition\" target=\"_blank\" title=\"\"><\/a><\/div><script id=\"script-row-unique-3\" data-row=\"script-row-unique-3\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-3\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-4\"><div class=\"row full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-69671992\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-102 tmb-id-2234 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/chun-ling-chou\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Chun-Ling Chou<\/h3><div class=\"t-entry-excerpt \"><p>Altersgruppe III (12-15 Jahre)<br \/>\n13 Jahre Taiwan<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-3988\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/1852-Chun-Ling-Chou-13-Jahre-Taiwan-uai-1089x817.png\" width=\"1089\" height=\"817\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-bottom pos-center align_left column_parent col-lg-5 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap heading-inline \"><div class=\"heading-text el-text\" ><h2 class=\"h2\" ><span><strong>Schaut euch unsere Preistr\u00e4ger des 58. Internationalen Zeichenwettbewerbs FLOW an!<\/strong><\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><span class=\"btn-container\" ><a role=\"button\"  href=\"https:\/\/flow-zeichenwettbewerb.de\/preistraeger\/\" class=\"custom-link btn btn-xl border-width-0 btn-color-vyce btn-flat btn-icon-right\" title=\"Preistr\u00e4ger\">Hier geht&#8217;s zu unseren Preistr\u00e4gern<i class=\"fa fa-arrow-right\"><\/i><\/a><\/span><div id=\"index-6967199\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-138 tmb-id-1549 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/nina-stiegler\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Nina Stiegler<\/h3><div class=\"t-entry-excerpt \"><p>Sonderkategorie Digital Art<br \/>\n16 Jahre \u00d6sterreich<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-4021\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/D-22-Nina-Stiegler-16-Jahre-Deutschland-scaled-uai-1810x1357.jpg\" width=\"1810\" height=\"1357\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-4\" data-row=\"script-row-unique-4\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-4\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-5\"><div class=\"row full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-696719\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-102 tmb-id-2237 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/yasmina-podlobco\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Yasmina Podlobco<\/h3><div class=\"t-entry-excerpt \"><p>Altersgruppe III (12-15 Jahre)<br \/>\n12 Jahre Deutschland<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-3983\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/Yasmina-Podlobco-12-Jahre-Deutschland-uai-947x710.png\" width=\"947\" height=\"710\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-bottom pos-center align_left column_parent col-lg-5 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-696719\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-104 tmb-id-2267 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/noemi-logge\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Noemi Logge<\/h3><div class=\"t-entry-excerpt \"><p>Altersgruppe IV (16-20 Jahre)<br \/>\n17 Jahre Deutschland<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-4007\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/Noemi-Logge-17-Jahre-Deutschland-uai-1168x876.png\" width=\"1168\" height=\"876\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-5\" data-row=\"script-row-unique-5\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-5\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-6\"><div class=\"row single-top-padding single-bottom-padding single-h-padding full-width row-parent\"><div class=\"wpb_row shift_y_neg_quad row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter z_index_2\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn\" ><div class=\"uncont single-block-padding col-custom-width style-color-120807-bg has-bg\" style=\" max-width:71%;\" ><div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><p class=\"h2 text-color-xsdn-color\" ><span>Der Internationale Zeichenwettbewerb FLOW, mit seinem Sitz in Schwedt\/Oder, z\u00e4hlt zu den bedeutendsten und \u00e4ltesten Zeichenwettbewerben in Deutschland.<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><p class=\"h4 text-color-xsdn-color\" ><span>J\u00e4hrlich senden rund 2000 Kinder und Jugendliche aus aller Welt ihre Arbeiten mit den unterschiedlichsten Techniken und zu den\u00a0verschiedensten Themen nach Schwedt.<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-6\" data-row=\"script-row-unique-6\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-6\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-7\"><div class=\"row full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-696719\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-98 tmb-id-2142 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"600\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/emma-breuer\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Emma Breuer<\/h3><div class=\"t-entry-excerpt \"><p>Altersgruppe I (4-6 Jahre)<br \/>\n6 Jahre Deutschland<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-3944\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/Emma-Breuer-6-Jahre-Deutschland-uai-1080x810.png\" width=\"1080\" height=\"810\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-bottom pos-center align_left column_parent col-lg-5 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-696719\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-100 tmb-id-2207 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside animate_when_almost_visible bottom-t-top\" data-delay=\"600\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 74.9%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/hong-rui-yu\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Hong Rui Yu<\/h3><div class=\"t-entry-excerpt \"><p>Altersgruppe II (7-11 Jahre)<br \/>\n8 Jahre Taiwan<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-3962\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/Hong-Rui-Yu-8-Jahre-Taiwan-min-uai-786x589.png\" width=\"786\" height=\"589\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-7\" data-row=\"script-row-unique-7\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-7\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-8\"><div class=\"row single-top-padding single-bottom-padding single-h-padding full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-5 boomapps_vccolumn single-internal-gutter z_index_2\"><div class=\"uncol style-light shift_x_quad shift_y_neg_quad\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn single-block-padding style-color-370045-bg has-bg\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><p class=\"h2 text-color-xsdn-color\" ><span>Neben der Jahresausstellung in den Uckerm\u00e4rkischen B\u00fchnen sind die Werke der jungen K\u00fcnstler auch auf Sonderausstellungen in ganz Deutschland und im Ausland zu sehen.<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><span class=\"btn-container animate_when_almost_visible zoom-in\" ><a role=\"button\"  href=\"https:\/\/flow-zeichenwettbewerb.de\/ausstellungen\/\" class=\"custom-link btn border-width-0 btn-color-152864 btn-flat btn-icon-right\" title=\"Ausstellungen\">Hier geht&#8217;s zu den Ausstellungen<i class=\"fa fa-calendar\"><\/i><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light shift_x_neg_quad\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-696719\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-130 grid-cat-106 tmb-id-2270 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside animate_when_almost_visible right-t-left\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/gruppenpreis-2025\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Gruppenpreis 2025<\/h3><div class=\"t-entry-excerpt \"><p>Kita \u201cKinderarche\u201d Schwedt\/Oder<br \/>\nSonnengruppe<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-4023\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/Gruppenpreis-uai-800x600.png\" width=\"800\" height=\"600\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-8\" data-row=\"script-row-unique-8\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-8\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-9\"><div class=\"row single-top-padding no-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light shift_y_neg_quad\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div id=\"index-696719\" class=\"isotope-system isotope-general-light grid-general-light\" >\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"isotope-container grid-container isotope-layout style-masonry isotope-pagination grid-pagination\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\" data-vp-height=\"\">\t\t\t<div class=\"tmb atc-typography-inherit tmb-iso-w12 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-center tmb-bordered  grid-cat-130 grid-cat-116 tmb-id-2301 tmb-img-ratio tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 75.1%;\"><\/div><a href=\"https:\/\/flow-zeichenwettbewerb.de\/en\/portfolio\/sonderpreis-des-ministeriums-fuer-bildung-jugend-und-sport-des-landes-brandenburg-2025\/\"  class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><div class=\"t-overlay-wrap\"><div class=\"t-overlay-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t-overlay-text single-block-padding\"><div class=\"t-entry\"><h3 class=\"t-entry-title h6 title-scale \">Sonderpreis des Ministeriums f\u00fcr Bildung, Jugend und Sport des Landes Brandenburg 2025<\/h3><div class=\"t-entry-excerpt \"><p>Piotr Lesniewski, 11 Jahre, Deutschland<br \/>\nFilip Filipowicz, 11 Jahre, Deutschland<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" class=\"wp-image-4038\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2025\/09\/Sonderpreis-MBJS-uai-538x404.png\" width=\"538\" height=\"404\" alt=\"\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-5 boomapps_vccolumn single-internal-gutter z_index_4\"><div class=\"uncol style-light shift_x_neg_double\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn single-block-padding style-color-120807-bg has-bg\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><p class=\"h3 text-color-xsdn-color\" ><span>Bei der hohen Qualit\u00e4t der eingereichten Arbeiten fiel uns die Auswahl nicht leicht.<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><span class=\"btn-container animate_when_almost_visible zoom-in\" ><a role=\"button\"  href=\"https:\/\/flow-zeichenwettbewerb.de\/preistraeger\/altersgruppe-i-4-6-jahre\/\" class=\"custom-link btn border-width-0 btn-color-122379 btn-flat btn-icon-right\" title=\"Altersgruppe I (4-6 Jahre)\">Hier geht&#8217;s zu den Preistr\u00e4gern<i class=\"fa fa-trophy\"><\/i><\/a><\/span><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-9\" data-row=\"script-row-unique-9\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-9\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-10\"><div class=\"row col-half-gutter single-top-padding single-bottom-padding single-h-padding full-width row-parent\"><div class=\"wpb_row shift_y_quad row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-5 boomapps_vccolumn single-internal-gutter z_index_2\"><div class=\"uncol style-light shift_x_quad shift_y_neg_quad\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn single-block-padding style-color-122379-bg has-bg\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><p class=\"h2 text-color-xsdn-color\" ><span>Unsere Youtube Videos<\/span><\/p><\/div><div class=\"clear\"><\/div><\/div><span class=\"btn-container animate_when_almost_visible zoom-in\" ><a role=\"button\"  href=\"https:\/\/www.youtube.com\/channel\/UC0HlUju9YgviF_bbHIimj2Q\" class=\"custom-link btn border-width-0 btn-color-120807 btn-flat btn-icon-right\" title=\"Videos_Youtube\" target=\"_blank\">Hier geht&#8217;s zu den Videos<i class=\"fa fa-play-circle-o\"><\/i><\/a><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light shift_x_neg_quad\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left animate_when_almost_visible bottom-t-top\" data-speed=\"600\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-1911\" src=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2020\/10\/DSC_3984.jpg\" width=\"1000\" height=\"664\" alt=\"\" srcset=\"https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2020\/10\/DSC_3984.jpg 1000w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2020\/10\/DSC_3984-300x199.jpg 300w, https:\/\/flow-zeichenwettbewerb.de\/wp-content\/uploads\/2020\/10\/DSC_3984-768x510.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-10\" data-row=\"script-row-unique-10\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-10\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-11\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-11\" data-row=\"script-row-unique-11\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-11\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Sonderpreis des Ministeriums f\u00fcr Bildung, Jugend und Sport des Landes Brandenburg Piotr Lesniewski 11 Jahre, Deutschland Filip Filipowicz 11 Jahre, [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":302,"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":4331,"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/pages\/2\/revisions\/4331"}],"wp:attachment":[{"href":"https:\/\/flow-zeichenwettbewerb.de\/en\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}